{"id":805,"date":"2017-06-29T17:35:01","date_gmt":"2017-06-29T17:35:01","guid":{"rendered":"http:\/\/espiritualidade.carmelitas.pt\/boletim\/?p=805"},"modified":"2017-06-29T17:35:01","modified_gmt":"2017-06-29T17:35:01","slug":"ligar-a-vida-a-biblia","status":"publish","type":"post","link":"https:\/\/espiritualidade.carmelitas.pt\/boletim\/ligar-a-vida-a-biblia\/","title":{"rendered":"Ligar a vida \u00e0 B\u00edblia"},"content":{"rendered":"<p><em>Armindo Vaz, OCD<\/em><\/p>\n<p>O ser humano, ao longo da vida, na actividade profissional, nas rela\u00e7\u00f5es humanas, para viajar, para fugir a perigos, para fazer as melhores op\u00e7\u00f5es, para ensinar e educar\u2026, precisa de guias, de guide lines, de indica\u00e7\u00f5es, de mapas, de um GPS. O que anda perdido na floresta, se encontra outro perdido sobrevivente, adverte-o na sua procura de caminho para casa: por aqui n\u00e3o v\u00e1s que de l\u00e1 j\u00e1 venho eu e n\u00e3o encontrei via de sa\u00edda. Mas tamb\u00e9m h\u00e1 os desencontrados consigo pr\u00f3prios que tentam recuperar a mem\u00f3ria regeneradora.<br \/>\nPara fugirmos a confus\u00f5es evit\u00e1veis, para n\u00e3o termos a sensa\u00e7\u00e3o de viver num caos desesperador ou ao sabor de mar\u00e9s e de modas, para n\u00e3o cairmos todos nos mesmos erros na vida e na procura de sentido para a vida, os humanos foram desenhando guias de orienta\u00e7\u00e3o e de programa\u00e7\u00e3o da pr\u00f3pria vida. O fil\u00f3sofo e te\u00f3logo judeu Maim\u00f3nides (1138-1204) escreveu mesmo o \u00abGuia de perdidos\u00bb, tresmalhados, perplexos.<br \/>\nNo campo da religiosidade, tamb\u00e9m os fi\u00e9is das v\u00e1rias religi\u00f5es, a partir da sua capta\u00e7\u00e3o do divino mediante a f\u00e9 e a luz do Esp\u00edrito, foram constituindo e instituindo colect\u00e2neas de livros, considerados revela\u00e7\u00e3o do Transcendente para encaminhar as pessoas pelos caminhos de vida e para afast\u00e1-las dos caminhos de perdi\u00e7\u00e3o. Foi assim que na religi\u00e3o judeo-crist\u00e3 a f\u00e9 do povo de Israel e da Igreja apost\u00f3lica formou ao longo de mais de dez s\u00e9culos a sua B\u00edblia, os seus livros sagrados. A partir do fim do s\u00e9c. II d.C. o juda\u00edsmo j\u00e1 tinha fixado o seu \u00abc\u00e2none\u00bb e os crist\u00e3os fixaram o seu em meados do s\u00e9c. V.<br \/>\nOs deuses das religi\u00f5es contempor\u00e2neas e do mesmo contexto hist\u00f3rico-geogr\u00e1fico em que foi escrita a B\u00edblia t\u00eam as suas imagens gravadas na pedra e desafiam o tempo nos templos que lhes foram dedicados ou nos museus que conservam a sua mem\u00f3ria. O Deus da religi\u00e3o b\u00edblica foi escutado na ora\u00e7\u00e3o e na medita\u00e7\u00e3o ao longo de s\u00e9culos e a sua \u00abpalavra viva\u00bb foi registada em textos, pouco a pouco compilados e reelaborados em Escritura poderosa, portadora de sentido. L\u00e1 est\u00e1 estampado, em v\u00e1rios g\u00e9neros de narrativa, o sentido \u00faltimo da vida e a raz\u00e3o \u00faltima da f\u00e9 judaica e crist\u00e3. Sobretudo ao referir-se \u00e0 vida e obra de Jesus, \u00e9 uma palavra com poder insuper\u00e1vel: \u201cA Palavra era a luz verdadeira que, vindo a este mundo, ilumina todos os seres humanos\u2026 A todos os que a receberam deu-lhes o poder de se tornarem filhos de Deus, \u00e0queles que aderem com a vida \u00e0 sua pessoa\u201d (Jo 1,9-12).<br \/>\nEste \u00abguia\u00bb que \u00e9 a Sagrada Escritura assume conscientemente o estatuto de revela\u00e7\u00e3o transcendente, pois realmente s\u00f3 assim consegue a sua finalidade, que \u00e9 a de ancorar o imanente no Transcendente, o relativo no Absoluto, a finitude no Infinito, o transit\u00f3rio no Imut\u00e1vel, o imponder\u00e1vel no Necess\u00e1rio, o absurdo no desassombro. Consultando assiduamente este guia, o leitor sente-se um ser novo, constantemente restitu\u00eddo ao Princ\u00edpio: \u201cpelo teu nome guias-me e diriges-me\u201d (Sl 31,4).<br \/>\nUma vez que a B\u00edblia foi nascendo da vida para generosamente fecundar a vida, se n\u00e3o a tivermos como b\u00fassola n\u00e3o admira que tantos crentes andem \u00e0 deriva pelos caminhos da vida, desandando frequentemente para a ang\u00fastia, para o desespero e para o absurdo. Conscientes de que as encruzilhadas dos nossos caminhos tornam muito complexa a rede de op\u00e7\u00f5es a fazer e de imponder\u00e1veis que se nos imp\u00f5em, resta sempre verdade que olhar para o mapa abre novos caminhos para sair da escurid\u00e3o e da afli\u00e7\u00e3o:<br \/>\n\u201cMostra-me, Senhor, o caminho que hei-de seguir,<br \/>\npois estou pendente dele\u201d (Sl 143,8);<br \/>\n\u201cafasta-me do caminho da mentira,<br \/>\nd\u00e1-me a gra\u00e7a da tua instru\u00e7\u00e3o;<br \/>\nescolhi o caminho da lealdade:<br \/>\nconformo-me \u00e0s tuas disposi\u00e7\u00f5es\u201d (Sl 119,29-32).<\/p>\n<p>\u00abGuia de perdidos\u00bb!? A Sagrada Escritura conta a hist\u00f3ria de muitos perdidos que se foram reencontrando em Deus. Mas tem uma proposta universal, especialmente no evangelho de Jesus. Na aventura existencial de cada ser humano, Jesus antecipa-se \u00e0 desventura de algu\u00e9m se perder e mostra-lhe a ventura que consiste em segui-lo: \u201cquem me segue n\u00e3o anda nas trevas mas ter\u00e1 a luz da vida\u201d (Jo 8,12), \u00e9 amado incondicionalmente, sempre e em qualquer circunst\u00e2ncia do caminho. Se se perde, soam logo todos os alarmes celestes: \u201cdeixa as noventa e nove nos montes para ir procurar a ovelha que se extraviou. Eu vos asseguro que, ao encontr\u00e1-la, sente mais alegria por ela do que pelas noventa e nove que n\u00e3o se extraviaram. A vontade do vosso Pai celeste \u00e9 de que n\u00e3o se perca nem um s\u00f3 destes pequeninos\u201d (Mt 18,12-14).<br \/>\nOu seja, o guia que se apresenta na B\u00edblia n\u00e3o \u00e9 s\u00f3 mapa que orienta: \u00e9 uma Pessoa que ama e vibra de alegria no encontro com cada ser humano. A vida alimenta-se do sentido que nela encontramos. A f\u00e9 e a esperan\u00e7a oferecidas pela revela\u00e7\u00e3o b\u00edblica ajudam a encontr\u00e1-lo no Amor recebido e dado, na medida em que aprendermos a viver do Amor e no amor. Jesus mostrou com o seu estilo de vida que o vazio n\u00e3o \u00e9 a vida: vazio \u00e9 viv\u00ea-la sem esperan\u00e7a e sem amor.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Armindo Vaz, OCD O ser humano, ao longo da vida, na actividade profissional, nas rela\u00e7\u00f5es humanas, para viajar, para fugir a perigos, para fazer as melhores op\u00e7\u00f5es, para ensinar e [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":806,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[4],"tags":[],"class_list":["post-805","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos","et-has-post-format-content","et_post_format-et-post-format-standard"],"_links":{"self":[{"href":"https:\/\/espiritualidade.carmelitas.pt\/boletim\/wp-json\/wp\/v2\/posts\/805","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espiritualidade.carmelitas.pt\/boletim\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espiritualidade.carmelitas.pt\/boletim\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espiritualidade.carmelitas.pt\/boletim\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/espiritualidade.carmelitas.pt\/boletim\/wp-json\/wp\/v2\/comments?post=805"}],"version-history":[{"count":1,"href":"https:\/\/espiritualidade.carmelitas.pt\/boletim\/wp-json\/wp\/v2\/posts\/805\/revisions"}],"predecessor-version":[{"id":807,"href":"https:\/\/espiritualidade.carmelitas.pt\/boletim\/wp-json\/wp\/v2\/posts\/805\/revisions\/807"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espiritualidade.carmelitas.pt\/boletim\/wp-json\/wp\/v2\/media\/806"}],"wp:attachment":[{"href":"https:\/\/espiritualidade.carmelitas.pt\/boletim\/wp-json\/wp\/v2\/media?parent=805"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espiritualidade.carmelitas.pt\/boletim\/wp-json\/wp\/v2\/categories?post=805"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espiritualidade.carmelitas.pt\/boletim\/wp-json\/wp\/v2\/tags?post=805"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}